{"id":9496,"date":"2023-09-30T00:39:47","date_gmt":"2023-09-29T22:39:47","guid":{"rendered":"https:\/\/linux-bibel.at\/?p=9496"},"modified":"2024-05-24T22:30:46","modified_gmt":"2024-05-24T20:30:46","slug":"texte-mit-whisper-unter-linux-diktieren","status":"publish","type":"post","link":"https:\/\/linux-bibel.at\/index.php\/2023\/09\/30\/texte-mit-whisper-unter-linux-diktieren\/","title":{"rendered":"Texte mit Whisper unter Linux diktieren"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Vom eigenen Gesprochenen eine Audio-Aufnahme zu erstellen, ist unter Linux das Einfachste. Hin und wieder braucht man diese Aufnahme auch als geschriebenen Text. F\u00fcr diesen Fall braucht man schon etwas anderes an Software &#8211; unter Linux ist aktuell daf\u00fcr die beste Software Whisper.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie sprechen nur noch den Text ins Mikrofon, und die Software schreibt Ihre Worte in eine Textdatei.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Whisper installieren<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Unter auf Debian basierenden Linux-Distributionen installieren Sie \u00fcber die Paket-Verwaltung die Pakete &#8222;<strong>build-essential ffmpeg<\/strong> <strong>git<\/strong>&#8222;, etwa gleich als root am Terminal mit dem Befehl:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>apt install build-essential ffmpeg git<\/code><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">Anschlie\u00dfend laden Sie die eigentliche Software mit normalen Benutzerrechten herunter:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>git clone https:\/\/github.com\/ggerganov\/whisper.cpp.git<\/code><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">Jetzt wechseln Sie in das heruntergeladene Verzeichnis:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>cd whisper.cpp<\/code><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">Bisher haben Sie nur die eigentliche Software heruntergeladen, dazu geh\u00f6rt noch das \u00dcbersetzungsmodell. Dieses gibt es in vier verschiedenen Varianten und wurde von ChatGPT entwickelt. Die Modelle unterscheiden sich in Dateigr\u00f6\u00dfe und ben\u00f6tigtem RAM. Je gr\u00f6\u00dfer die Datei, desto mehr RAM ben\u00f6tigt das Modell. Und je gr\u00f6\u00dfer die Datei, desto besser ist aber auch  die Erkennung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Modelle nennen sich <em>tiny<\/em> (<em>80 MB, ben\u00f6tigt rund 130 MB RAM<\/em>), <em>base<\/em>, <em>small<\/em>, <em>medium<\/em> und <em>large<\/em> (<em>2,9 GB, ben\u00f6tigt rund 3,3 GB RAM<\/em>). <em>large<\/em> hat nat\u00fcrlich die beste Erkennung. Jetzt gilt es, die Software mit dem gew\u00fcnschten Modell zu kompilieren &#8211; hierzu nutzen Sie den Befehl make mit dem gew\u00fcnschten Modell, also etwa (<em>als normaler Benutzer<\/em>):<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>make tiny<\/code><\/pre>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2023\/09\/whisper-scaled.jpeg\" rel=\"lightbox-0\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"440\" src=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2023\/09\/whisper-1024x440.jpeg\" alt=\"\" class=\"wp-image-9499\" srcset=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2023\/09\/whisper-1024x440.jpeg 1024w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2023\/09\/whisper-300x129.jpeg 300w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2023\/09\/whisper-150x64.jpeg 150w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2023\/09\/whisper-768x330.jpeg 768w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2023\/09\/whisper-1536x660.jpeg 1536w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2023\/09\/whisper-2048x880.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Das angegebene Modell wird dabei automatisch aus dem Netz geladen und die Software kompiliert. Anschlie\u00dfend verschieben Sie das komplette Verzeichnis als root auf dem Terminal nach <em>\/opt<\/em>:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>cd ..\nmv whisper.cpp\/ whisper\nmv whisper\/ \/opt\/<\/code><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">Damit Sie nicht f\u00fcr jeden Start der Software zweimal den langen Pfad \u00fcber \/opt angeben m\u00fcssen, erstellen Sie noch einen <a href=\"https:\/\/linux-bibel.at\/index.php\/2023\/09\/10\/symbolische-links-und-hardlinks-unter-linux\/\" data-type=\"post\" data-id=\"2395\">Symlink<\/a> von <strong>main<\/strong> auf <strong>whisper<\/strong> (<em>ebenfalls als root<\/em>):<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>cd \/usr\/local\/bin\/\nln -s \/opt\/whisper\/main whisper<\/code><\/pre>\n\n\n\n<h3 class=\"wp-block-heading\">Whisper nutzen<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sie starten die Software auf dem Terminal, nach dem Start braucht die Software etwa 15 Sekunden und ist bereit. Mit <code>-t<\/code> geben Sie die zu nutzenden CPU-Kerne an, mit <code>-m<\/code> das Modell &#8211; dieses liegt unter <em>\/opt\/whisper\/models\/<\/em> und beginnt mit &#8222;<strong>ggml-modell.bin<\/strong>&#8222;, in meinem Beispiel also &#8222;<strong>ggml-tiny.bin<\/strong>&#8222;. Mit <code>-l<\/code> geben Sie die Sprache an, etwa <strong>de<\/strong>, es folgt die Option <code>-otxt<\/code> und mit <code>-of<\/code> geben Sie die zu erstellende Textdatei an &#8211; etwa <strong>Textdatei.txt<\/strong>. Zum Schluss folgt die zu erstellende Audio-Datei &#8211; im Beispiel ganz einfach <strong>Audio.wav<\/strong>, Beispiel:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>whisper -t 4 -m \/opt\/whisper\/models\/ggml-tiny.bin -l de -otxt -of Textdatei.txt Audio.wav<\/code><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">Die Software nimmt Ihren gesprochenen Text in die Datei Audio.wav auf, schreibt den erkannten Text in die Datei Textdatei.txt. Sobald die Software fertig ist, beendet sich diese selbst. Dies dauert nat\u00fcrlich etwas, funktioniert jedoch schon pr\u00e4chtig.<\/p>\n<div class=\"pld-like-dislike-wrap pld-custom\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Gef\u00e4llt mir\" data-post-id=\"9496\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\">\r\n                            <img src=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2023\/12\/Daumen-Hoch.png\" alt=\"Gef\u00e4llt mir\" \/>\r\n            <\/a>\r\n    <span class=\"pld-like-count-wrap pld-count-wrap\">3    <\/span>\r\n<\/div><div class=\"pld-dislike-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-dislike-trigger pld-like-dislike-trigger  \" title=\"Gef\u00e4llt mir nicht\" data-post-id=\"9496\" data-trigger-type=\"dislike\" data-restriction=\"cookie\" data-already-liked=\"0\">\r\n                            <img src=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2023\/12\/Daumen-Runter.png\" alt=\"Gef\u00e4llt mir nicht\" \/>\r\n            <\/a>\r\n    <span class=\"pld-dislike-count-wrap pld-count-wrap\">1<\/span>\r\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Vom eigenen Gesprochenen eine Audio-Aufnahme zu erstellen, ist unter Linux das Einfachste. Hin und wieder braucht man diese Aufnahme auch als geschriebenen Text. F\u00fcr diesen Fall braucht man schon etwas anderes an Software &#8211; unter Linux ist aktuell daf\u00fcr die beste Software Whisper. Sie sprechen nur noch den Text ins Mikrofon, und die Software schreibt [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9500,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57],"tags":[59],"class_list":["post-9496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-buero","tag-buero"],"_links":{"self":[{"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/posts\/9496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/comments?post=9496"}],"version-history":[{"count":2,"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/posts\/9496\/revisions"}],"predecessor-version":[{"id":15404,"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/posts\/9496\/revisions\/15404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/media\/9500"}],"wp:attachment":[{"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/media?parent=9496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/categories?post=9496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/tags?post=9496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}