{"id":17839,"date":"2025-01-18T09:52:09","date_gmt":"2025-01-18T08:52:09","guid":{"rendered":"https:\/\/linux-bibel.at\/?p=17839"},"modified":"2025-01-18T09:52:11","modified_gmt":"2025-01-18T08:52:11","slug":"jan-lokale-alternative-zu-chatgpt-gemini-microsoft-copilot-und-co-unter-linux","status":"publish","type":"post","link":"https:\/\/linux-bibel.at\/index.php\/2025\/01\/18\/jan-lokale-alternative-zu-chatgpt-gemini-microsoft-copilot-und-co-unter-linux\/","title":{"rendered":"Jan &#8211; lokale Alternative zu ChatGPT, Gemini, Microsoft Copilot und Co. unter Linux"},"content":{"rendered":"\n<p>K&uuml;nstliche Intelligenz &ndash; kurz einfach <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/ki\/\" target=\"_self\" title='Unter \"KI\" versteht man \"K&uuml;nstliche Intelligenz\". Es handelt sich um ein Teilgebiet der Informatik, das sich mit der Automatisierung intelligenten Lern- und Entscheidungsverhaltens besch&auml;ftigt. KI erm&ouml;glicht es technischen Systemen, ihre Umwelt wahrzunehmen, mit dem Wahrgenommenen umzugehen und darauf basierend Entscheidungen zu treffen. KI wird in verschiedenen Bereichen eingesetzt, wie zum Beispiel in der Medizin zur&hellip;' class=\"encyclopedia\">KI<\/a> ist so gut wie &uuml;berall im Gespr&auml;ch, nur will nicht jeder seine <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/daten\/\" target=\"_self\" title='Unter \"Daten\" versteht man Informationen, die auf dem Dateisystem gespeichert sind. Diese Informationen k&ouml;nnen in Form von Dateien oder Verzeichnissen vorliegen. Linux verwendet ein hierarchisches Dateisystem, das sich von dem in Windows unterscheidet. Das Wurzelverzeichnis \"\/\" ist der oberste Verzeichnisbaum, von dem aus alle anderen Verzeichnisse und Dateien abzweigen.' class=\"encyclopedia\">Daten<\/a> preisgeben. Jan ist eine freie Alternative &ndash; und, Jan l&auml;uft lokal, braucht keine Anbindung zum Internet, keine Anmeldung, &hellip; Eine bessere Grafikkarte ist bei lokalen Sprachmodellen vom Vorteil, aber nicht unbedingt n&ouml;tig, ein halbwegs aktueller Rechner w&auml;re nat&uuml;rlich gut.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Jan installieren<\/h3>\n\n\n\n<p>Sie finden Jan auf <a href=\"https:\/\/github.com\/janhq\/jan\/releases\" target=\"_blank\" rel=\"noreferrer noopener\">GitHub<\/a> zum Download &ndash; hier finden Sie ein <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/deb\/\" target=\"_self\" title=\"DEB (*.deb) ist das Dateiformat f&uuml;r Softwarepakete, die in Debian-basierten Linux-Distributionen verwendet werden. Es handelt sich um Installationsdateien, die eine Software zur Installation auf Debian-basierten Systemen enthalten. DEB-Pakete sind in etwa vergleichbar mit .exe-Dateien unter Windows - sie beinhalten die zu installierende Software sowie Metadaten. Sie werden von der Debian-Paketverwaltung (dpkg) und Tools wie apt&hellip;\" class=\"encyclopedia\">DEB<\/a>-<a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/pakete\/\" target=\"_self\" title=\"Unter Linux sind Pakete die grundlegenden Bausteine von Software, die von einem Paketmanager verwaltet werden. Ein Paket enth&auml;lt die ausf&uuml;hrbaren Dateien, Konfigurationsdateien, Dokumentation und Metadaten, die f&uuml;r die Installation und Verwaltung der Software ben&ouml;tigt werden.\" class=\"encyclopedia\">Paket<\/a> f&uuml;r <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/debian\/\" target=\"_self\" title=\"Debian ist eine freie Linux-Distribution, die von einer Gemeinschaft von Freiwilligen entwickelt wird. Es wird h&auml;ufig als Basis f&uuml;r andere Distributionen wie Ubuntu verwendet und ist bekannt f&uuml;r seine Zuverl&auml;ssigkeit und Stabilit&auml;t. Debian bietet eine Vielzahl von Anwendungen und Werkzeugen, die f&uuml;r die Verwendung in verschiedenen Umgebungen geeignet sind, von Desktop-Computern bis hin zu Server-Systemen.&hellip;\" class=\"encyclopedia\">Debian<\/a>, Ubuntu und darauf basierende <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/linux\/\" target=\"_self\" title=\"Linux ist ein UNIX-artiges Betriebssystem, seine Entwicklung wurde im Jahr 1992 vom Finnen Linus Torwalds gestartet. Im Grunde handelt es sich bei Linux nur um den Kern des Betriebssystems, zum Arbeiten ben&ouml;tigt Linux noch Treiber und Software, nicht unbedingt n&ouml;tig ist eine grafische Oberfl&auml;che.\" class=\"encyclopedia\">Linux<\/a>-<a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/distribution\/\" target=\"_self\" title=\"Linux-Distributionen basieren auf dem Linux-Kernel, erg&auml;nzt mit weiteren Komponenten wie Installationsprogrammen, Verwaltungswerkzeugen und zus&auml;tzlicher Software. Sie bieten Unterst&uuml;tzung durch den Distributor, haben ihre eigenen Merkmale und Zielgruppen. Als Alternative zu propriet&auml;ren Betriebssystemen wie Windows und macOS sind diese i.d.R. kostenlos, Open-Source mit gro&szlig;er Auswahl an Anwendungs-Software. Viele Linux-Distributionen werden zudem von einer aktiven Community entwickelt&hellip;\" class=\"encyclopedia\">Distribution<\/a>en, sowie auch ein <a href=\"https:\/\/linux-bibel.at\/index.php\/2023\/09\/09\/appimage-universelle-software-pakete-fuer-alle-linux-distributionen\/\" data-type=\"post\" data-id=\"1823\">Appimage<\/a>. Das heruntergeladene <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/deb\/\" target=\"_self\" title=\"DEB (*.deb) ist das Dateiformat f&uuml;r Softwarepakete, die in Debian-basierten Linux-Distributionen verwendet werden. Es handelt sich um Installationsdateien, die eine Software zur Installation auf Debian-basierten Systemen enthalten. DEB-Pakete sind in etwa vergleichbar mit .exe-Dateien unter Windows - sie beinhalten die zu installierende Software sowie Metadaten. Sie werden von der Debian-Paketverwaltung (dpkg) und Tools wie apt&hellip;\" class=\"encyclopedia\">DEB<\/a>-<a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/pakete\/\" target=\"_self\" title=\"Unter Linux sind Pakete die grundlegenden Bausteine von Software, die von einem Paketmanager verwaltet werden. Ein Paket enth&auml;lt die ausf&uuml;hrbaren Dateien, Konfigurationsdateien, Dokumentation und Metadaten, die f&uuml;r die Installation und Verwaltung der Software ben&ouml;tigt werden.\" class=\"encyclopedia\">Paket<\/a> installieren Sie wie gehabt ganz einfach per Mausklick oder als <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/root\/\" target=\"_self\" title=\"root ist der wahre Administrator, auch root-Benutzer unter Linux. Er alleine hat &uuml;ber das Betriebssystem alle Rechte. Zum Benutzer root wird man unter Linux auf dem Terminal mit dem Befehl: su Hat man kein root-Passwort angelegt, dient dazu der Befehl: sudo -i oder auch: sudo befehl\" class=\"encyclopedia\">root<\/a> auf dem <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/terminal\/\" target=\"_self\" title=\"Ein Terminal ist eine Benutzerschnittstelle, eine grafische Oberfl&auml;che, um &uuml;ber die Shell mit einem Interpreter direkt mit dem Betriebssystem zu kommunizieren. Grundlegend wird das Terminal mit der Tastatur bedient, einige Funktionen k&ouml;nnen je nach Terminal auch mit der Maus genutzt werden. Bekannte Terminals unter Linux w&auml;ren etwa die Konsole unter KDE, das GNOME-Terminal, Terminoligy unter&hellip;\" class=\"encyclopedia\">Terminal<\/a>:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>apt install \/home\/username\/Downloads\/jan-beta-linux-...beta.deb<\/code><\/pre>\n\n\n\n<p>Oder, wenn Sie sich bereits im <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/verzeichnis\/\" target=\"_self\" title=\"Ein Verzeichnis ist eine Datei, die andere Dateien und Verzeichnisse enth&auml;lt. Linux und Unix verwenden eine hierarchische, baumartige Struktur f&uuml;r das Dateisystem. Das h&ouml;chste Level des Dateisystems ist das Root-Verzeichnis (\/), unter dem alle anderen Dateien und Verzeichnisse existieren. Verzeichnisse sind Dateien und k&ouml;nnen im Root-Verzeichnis oder in anderen Verzeichnissen erstellt werden. Alles ist eine&hellip;\" class=\"encyclopedia\">Verzeichnis<\/a> mit der <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/datei\/\" target=\"_self\" title='Unter \"Datei\" versteht man eine Einheit, die Informationen oder Daten enth&auml;lt. Dateien k&ouml;nnen verschiedene Arten von Inhalten haben, wie Text, Bilder, Audiodateien oder ausf&uuml;hrbare Programme. In Linux werden Dateien in einem hierarchischen Dateisystem organisiert, das &auml;hnlich wie ein Verzeichnisbaum aufgebaut ist. Das Wurzelverzeichnis \"\/\" ist der oberste Knoten des Verzeichnisbaums und enth&auml;lt alle anderen Dateien&hellip;' class=\"encyclopedia\">Datei<\/a> auf dem <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/terminal\/\" target=\"_self\" title=\"Ein Terminal ist eine Benutzerschnittstelle, eine grafische Oberfl&auml;che, um &uuml;ber die Shell mit einem Interpreter direkt mit dem Betriebssystem zu kommunizieren. Grundlegend wird das Terminal mit der Tastatur bedient, einige Funktionen k&ouml;nnen je nach Terminal auch mit der Maus genutzt werden. Bekannte Terminals unter Linux w&auml;ren etwa die Konsole unter KDE, das GNOME-Terminal, Terminoligy unter&hellip;\" class=\"encyclopedia\">Terminal<\/a> befinden, etwas abgek&uuml;rzt:<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>apt install .\/jan-beta-...<\/code><\/pre>\n\n\n\n<p>Wie einfach Sie das <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/appimage\/\" target=\"_self\" title=\"AppImage ist ein Paketformat f&uuml;r Linux, das es erm&ouml;glicht, bin&auml;re Software unabh&auml;ngig von bestimmten Linux-Distributionen zu installieren und auszuf&uuml;hren. Im Gegensatz zu traditionellen Paketverwaltungen wie DEB oder RPM, die spezifisch f&uuml;r bestimmte Distributionen sind, ist ein AppImage eine eigenst&auml;ndige Datei, die alle Dateien enth&auml;lt, die f&uuml;r die Ausf&uuml;hrung der Anwendung erforderlich sind. Das bedeutet, dass&hellip;\" class=\"encyclopedia\">Appimage<\/a> unter allen anderen <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/linux\/\" target=\"_self\" title=\"Linux ist ein UNIX-artiges Betriebssystem, seine Entwicklung wurde im Jahr 1992 vom Finnen Linus Torwalds gestartet. Im Grunde handelt es sich bei Linux nur um den Kern des Betriebssystems, zum Arbeiten ben&ouml;tigt Linux noch Treiber und Software, nicht unbedingt n&ouml;tig ist eine grafische Oberfl&auml;che.\" class=\"encyclopedia\">Linux<\/a>-<a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/distribution\/\" target=\"_self\" title=\"Linux-Distributionen basieren auf dem Linux-Kernel, erg&auml;nzt mit weiteren Komponenten wie Installationsprogrammen, Verwaltungswerkzeugen und zus&auml;tzlicher Software. Sie bieten Unterst&uuml;tzung durch den Distributor, haben ihre eigenen Merkmale und Zielgruppen. Als Alternative zu propriet&auml;ren Betriebssystemen wie Windows und macOS sind diese i.d.R. kostenlos, Open-Source mit gro&szlig;er Auswahl an Anwendungs-Software. Viele Linux-Distributionen werden zudem von einer aktiven Community entwickelt&hellip;\" class=\"encyclopedia\">Distribution<\/a>en nutzen, lesen Sie am Link oben.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Jan nutzen<\/h3>\n\n\n\n<p>Sie finden Jan nach der Installation im Anwendungsmen&uuml; unter der Kategorie Dienstprog<a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/ram\/\" target=\"_self\" title=\"Der RAM oder Arbeitsspeicher ist ein essentieller Bestandteil eines Rechners, der als fl&uuml;chtiger und sehr schneller Speicher fungiert. Er erm&ouml;glicht es dem Computer, Daten sehr schnell zu lesen und zu ver&auml;ndern, und spielt eine entscheidende Rolle f&uuml;r die Leistungsf&auml;higkeit des Systems. Der Arbeitsspeicher ist ein tempor&auml;rer Speicher, was bedeutet, dass die gespeicherten Informationen verloren gehen,&hellip;\" class=\"encyclopedia\">ram<\/a>me (<em>KDE<\/em>) oder unter Zubeh&ouml;r (<em>andere <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/desktop\/\" target=\"_self\" title=\"Der Desktop bezieht sich auf die Benutzeroberfl&auml;che eines Betriebssystems. Dabei handelt es sich um eine grafische Arbeits- bzw. Benutzerumgebung, die eine visuelle Darstellung des Schreibtisches bietet. Es gibt eine Vielzahl von Desktop-Umgebungen f&uuml;r Linux, darunter GNOME, KDE, Xfce, Cinnamon, MATE und viele mehr. Jede Desktop-Umgebung bietet unterschiedliche Funktionen, Stile und Ressourcen-Anforderungen. Im Gegensatz zu Windows&hellip;\" class=\"encyclopedia\">Desktop<\/a>-Umgebungen<\/em>), das <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/appimage\/\" target=\"_self\" title=\"AppImage ist ein Paketformat f&uuml;r Linux, das es erm&ouml;glicht, bin&auml;re Software unabh&auml;ngig von bestimmten Linux-Distributionen zu installieren und auszuf&uuml;hren. Im Gegensatz zu traditionellen Paketverwaltungen wie DEB oder RPM, die spezifisch f&uuml;r bestimmte Distributionen sind, ist ein AppImage eine eigenst&auml;ndige Datei, die alle Dateien enth&auml;lt, die f&uuml;r die Ausf&uuml;hrung der Anwendung erforderlich sind. Das bedeutet, dass&hellip;\" class=\"encyclopedia\">Appimage<\/a> starten Sie einfach per Mausklick:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan.jpeg\" rel=\"lightbox-0\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"829\" src=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-1024x829.jpeg\" alt=\"\" class=\"wp-image-17840\" srcset=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-1024x829.jpeg 1024w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-150x121.jpeg 150w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-300x243.jpeg 300w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-768x622.jpeg 768w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan.jpeg 1042w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a><\/figure>\n\n\n\n<p>Bisher haben Sie eigentlich nur die eigentliche Software heruntergeladen und installiert, jetzt geht es zur Auswahl des eigentlichen Sprachmodells. Hier kann Jan solche nutzen, die nur lokal laufen (<em>on device modells<\/em>) und auch solche in der <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/cloud\/\" target=\"_self\" title=\"Eine Cloud (englisch: Wolke) ist ein digitaler zentraler Speicher, auf den &uuml;ber ein Netzwerk mit mehreren Ger&auml;ten zugegriffen werden kann. Vorteile einer Cloud Zwischen einer Cloud und den entsprechenden Endger&auml;ten besteht in der Regel keine physische Verbindung, d.h. die Daten&uuml;bertragung von und zu der Cloud geschieht &uuml;ber ein Netzwerk, meistens das Internet. Im Falle eines&hellip;\" class=\"encyclopedia\">Cloud<\/a> &ndash; also etwa <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/chatgpt\/\" target=\"_self\" title='Die Abk&uuml;rzung \"ChatGPT\" steht f&uuml;r \"Chatbot Generative Pre-trained Transformer\". ChatGPT ist ein KI-Chatbot, der auf der Technologie des Generative Pretrained Transformer basiert. Er kann mit Menschen kommunizieren und Fragen beantworten. ChatGPT ist ein kostenloser KI-Textgenerator, der beliebige Texte erzeugen kann und Antworten auf die meisten Fragen kennt. ChatGPT hat jedoch einige Einschr&auml;nkungen und es ist&hellip;' class=\"encyclopedia\">ChatGPT<\/a> und Co. F&uuml;r entsprechende <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/cloud\/\" target=\"_self\" title=\"Eine Cloud (englisch: Wolke) ist ein digitaler zentraler Speicher, auf den &uuml;ber ein Netzwerk mit mehreren Ger&auml;ten zugegriffen werden kann. Vorteile einer Cloud Zwischen einer Cloud und den entsprechenden Endger&auml;ten besteht in der Regel keine physische Verbindung, d.h. die Daten&uuml;bertragung von und zu der Cloud geschieht &uuml;ber ein Netzwerk, meistens das Internet. Im Falle eines&hellip;\" class=\"encyclopedia\">Cloud<\/a>-Modelle ben&ouml;tigen Sie nat&uuml;rlich einen Account &ndash; daf&uuml;r interessieren wir uns nat&uuml;rlich nicht, wir wollen lokale Modelle nutzen &ndash; klicken Sie neben &bdquo;<em>On-device Models<\/em>&ldquo; auf &bdquo;<strong>See All<\/strong>&bdquo;:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-1.jpeg\" rel=\"lightbox-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-1-1024x576.jpeg\" alt=\"\" class=\"wp-image-17841\" srcset=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-1-1024x576.jpeg 1024w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-1-1536x864.jpeg 1536w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-1-150x84.jpeg 150w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-1-300x169.jpeg 300w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-1-768x432.jpeg 768w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-1.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a><\/figure>\n\n\n\n<p>Die Liste der Sprachmodelle ist schon recht gro&szlig;, neben der Bezeichnung finden Sie rechts auch die Download-Gr&ouml;&szlig;e und den Schalter f&uuml;r den Download. Der Zusatz &bdquo;<em>Slow on your device<\/em>&ldquo; zeigt Ihnen, wahrscheinlich fehlt es an der Hardware (<em>Grafikkarte<\/em>). Gr&ouml;&szlig;ere Sprachmodelle haben nat&uuml;rlich auch mehr Wissen in der <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/datenbank\/\" target=\"_self\" title=\"Eine Datenbank ist eine organisierte Sammlung von strukturierten Informationen oder Daten, die in der Regel elektronisch in einem Computersystem gespeichert werden. Eine Datenbank wird normalerweise von einem Datenbankmanagementsystem (DBMS) kontrolliert. Zusammen mit den Anwendungen, die mit ihnen verbunden sind, werden die Daten und das DBMS als Datenbanksystem bezeichnet. Daten in den g&auml;ngigsten Datenbanktypen werden in&hellip;\" class=\"encyclopedia\">Datenbank<\/a> &ndash; eigentlich auch verst&auml;ndlich. Etwas mehr Informationen &uuml;ber ein Modell erhalten Sie, indem Sie dessen Namen anklicken:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-2.jpeg\" rel=\"lightbox-2\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"139\" src=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-2-1024x139.jpeg\" alt=\"\" class=\"wp-image-17842\" srcset=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-2-1024x139.jpeg 1024w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-2-1536x209.jpeg 1536w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-2-150x20.jpeg 150w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-2-300x41.jpeg 300w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-2-768x104.jpeg 768w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-2.jpeg 1787w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a><\/figure>\n\n\n\n<p>Ein Klick auf den Schalter &bdquo;<strong>Download<\/strong>&ldquo; und den Rest der Installation &uuml;bernimmt Jan, Sie k&ouml;nnen nat&uuml;rlich auch mehrere Sprachmodelle installieren und nutzen, installierte wieder &uuml;ber Bord werfen.<\/p>\n\n\n\n<p>Haben Sie eines oder mehrere Modelle heruntergeladen, oder eines in der <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/cloud\/\" target=\"_self\" title=\"Eine Cloud (englisch: Wolke) ist ein digitaler zentraler Speicher, auf den &uuml;ber ein Netzwerk mit mehreren Ger&auml;ten zugegriffen werden kann. Vorteile einer Cloud Zwischen einer Cloud und den entsprechenden Endger&auml;ten besteht in der Regel keine physische Verbindung, d.h. die Daten&uuml;bertragung von und zu der Cloud geschieht &uuml;ber ein Netzwerk, meistens das Internet. Im Falle eines&hellip;\" class=\"encyclopedia\">Cloud<\/a> zur Nutzung gew&auml;hlt, klicken Sie links oben auf den Schalter mit dem Chat-Symbol:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-3.jpeg\" rel=\"lightbox-3\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-3-1024x576.jpeg\" alt=\"\" class=\"wp-image-17843\" srcset=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-3-1024x576.jpeg 1024w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-3-1536x864.jpeg 1536w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-3-150x84.jpeg 150w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-3-300x169.jpeg 300w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-3-768x432.jpeg 768w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-3.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a><\/figure>\n\n\n\n<p>Haben Sie mehrere Modelle installiert, l&auml;sst sich im Eingabefeld das gew&uuml;nschte ausw&auml;hlen. Nutzen Sie ein <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/cloud\/\" target=\"_self\" title=\"Eine Cloud (englisch: Wolke) ist ein digitaler zentraler Speicher, auf den &uuml;ber ein Netzwerk mit mehreren Ger&auml;ten zugegriffen werden kann. Vorteile einer Cloud Zwischen einer Cloud und den entsprechenden Endger&auml;ten besteht in der Regel keine physische Verbindung, d.h. die Daten&uuml;bertragung von und zu der Cloud geschieht &uuml;ber ein Netzwerk, meistens das Internet. Im Falle eines&hellip;\" class=\"encyclopedia\">Cloud<\/a>-Modell, l&auml;sst sich dieses in den Einstellungen links unten (<em>der Schalter mit dem Zahnrad<\/em>) konfigurieren &ndash; etwa der API-Key eingeben:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-4.jpeg\" rel=\"lightbox-4\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-4-1024x576.jpeg\" alt=\"\" class=\"wp-image-17844\" srcset=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-4-1024x576.jpeg 1024w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-4-1536x864.jpeg 1536w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-4-150x84.jpeg 150w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-4-300x169.jpeg 300w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-4-768x432.jpeg 768w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-4.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a><\/figure>\n\n\n\n<p>Je nach Hardware kommen nach eingegebenen Fragen (<em>lokales Modell<\/em>) dann entsprechend schnell die Antworten. Ich habe am Testrechner 16 GB <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/ram\/\" target=\"_self\" title=\"Der RAM oder Arbeitsspeicher ist ein essentieller Bestandteil eines Rechners, der als fl&uuml;chtiger und sehr schneller Speicher fungiert. Er erm&ouml;glicht es dem Computer, Daten sehr schnell zu lesen und zu ver&auml;ndern, und spielt eine entscheidende Rolle f&uuml;r die Leistungsf&auml;higkeit des Systems. Der Arbeitsspeicher ist ein tempor&auml;rer Speicher, was bedeutet, dass die gespeicherten Informationen verloren gehen,&hellip;\" class=\"encyclopedia\">RAM<\/a> und 16 Kerne und eine AMD-Standard-Grafikkarte &ndash; mitlesen kann man bei einer solchen <a href=\"https:\/\/linux-bibel.at\/index.php\/enzyklopaedie\/konfiguration\/\" target=\"_self\" title='Unter \"Konfiguration\" in Linux versteht man die Einstellung und Anpassung verschiedener Parameter und Optionen, um das System oder eine Anwendung entsprechend den individuellen Anforderungen zu konfigurieren. Die Konfiguration kann sowohl hardwareseitig als auch softwareseitig erfolgen.' class=\"encyclopedia\">Konfiguration<\/a> fast nicht mehr, also ansprechend schnell:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-5.jpeg\" rel=\"lightbox-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-5-1024x576.jpeg\" alt=\"\" class=\"wp-image-17845\" srcset=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-5-1024x576.jpeg 1024w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-5-1536x864.jpeg 1536w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-5-150x84.jpeg 150w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-5-300x169.jpeg 300w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-5-768x432.jpeg 768w, https:\/\/linux-bibel.at\/wp-content\/uploads\/2025\/01\/jan-5.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/a><\/figure>\n\n\n\n<p>Hin und wieder sollten Sie unter den genutzten Modellen nat&uuml;rlich auch nachsehen, ob es Aktualisierungen zum Download gibt.<\/p>\n<div class=\"pld-like-dislike-wrap pld-custom\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger  \" title=\"Gef\u00e4llt mir\" data-post-id=\"17839\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\">\r\n                            <img src=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2023\/12\/Daumen-Hoch.png\" alt=\"Gef\u00e4llt mir\" \/>\r\n            <\/a>\r\n    <span class=\"pld-like-count-wrap pld-count-wrap\">12    <\/span>\r\n<\/div><div class=\"pld-dislike-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-dislike-trigger pld-like-dislike-trigger  \" title=\"Gef\u00e4llt mir nicht\" data-post-id=\"17839\" data-trigger-type=\"dislike\" data-restriction=\"cookie\" data-already-liked=\"0\">\r\n                            <img src=\"https:\/\/linux-bibel.at\/wp-content\/uploads\/2023\/12\/Daumen-Runter.png\" alt=\"Gef\u00e4llt mir nicht\" \/>\r\n            <\/a>\r\n    <span class=\"pld-dislike-count-wrap pld-count-wrap\"><\/span>\r\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>K\u00fcnstliche Intelligenz &#8211; kurz einfach KI ist so gut wie \u00fcberall im Gespr\u00e4ch, nur will nicht jeder seine Daten preisgeben. Jan ist eine freie Alternative &#8211; und, Jan l\u00e4uft lokal, braucht keine Anbindung zum Internet, keine Anmeldung, &#8230; Eine bessere Grafikkarte ist bei lokalen Sprachmodellen vom Vorteil, aber nicht unbedingt n\u00f6tig, ein halbwegs aktueller Rechner [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17845,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[628],"tags":[698],"class_list":["post-17839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kuenstliche-intelligenz","tag-kuenstliche-intelligenz"],"_links":{"self":[{"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/posts\/17839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/comments?post=17839"}],"version-history":[{"count":1,"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/posts\/17839\/revisions"}],"predecessor-version":[{"id":17846,"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/posts\/17839\/revisions\/17846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/media\/17845"}],"wp:attachment":[{"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/media?parent=17839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/categories?post=17839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/linux-bibel.at\/index.php\/wp-json\/wp\/v2\/tags?post=17839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}